{"id":28347,"date":"2020-11-24T14:28:33","date_gmt":"2020-11-24T13:28:33","guid":{"rendered":"http:\/\/webtrial.emecpumps.com\/wordpress\/simple-as-water\/"},"modified":"2022-02-08T23:15:01","modified_gmt":"2022-02-08T22:15:01","slug":"simple-as-water","status":"publish","type":"page","link":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/","title":{"rendered":"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; pix_particles_check=&#8221;&#8221; css=&#8221;.vc_custom_1616411280682{background-color: #000000 !important;}&#8221;][vc_column][vc_column_text]\r\n<div style=\"width: 100vw; height: 100vh; background: #000; position: relative;\">\r\n<div class=\"titoletto\">\r\n\r\n<img decoding=\"async\" class=\"cursor\" src=\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/06\/scroll.png\" alt=\"Cursor\" \/>\r\n<img decoding=\"async\" class=\"alignnone size-full wp-image-18164\" src=\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/03\/emec-lo.jpg\" alt=\"\" width=\"150\" height=\"159\" \/>\r\n<h4 style=\"color: #fff;\">Scroll Down<\/h4>\r\n&nbsp;\r\n<div class=\"scrollo\"><\/div>\r\n<\/div>\r\n<\/div>\r\n\n\n<!-- Scrollsequence WP Plugin  -->\n<scrollsequence >\t\n\n\t\t\t\n  <style>\n  \t.scrollsequence-pages-wrap {height:100vh}\n  \t.scrollsequence-page {position:absolute;display:none}\n\n\t.gsap-marker-scroller-start {z-index:999999!important;} \n  <\/style>\t\t\t\n  <noscript> \n\t  <style>\n\t  .scrollsequence-wrap {height:initial!important;}\n\t  .scrollsequence-pages-wrap {height:initial}\n\t  .scrollsequence-page {position:relative;opacity:initial;display:block  ;visibility:initial}\t   \n\t  <\/style> \n  <\/noscript>\n\n  <div style=\"position: fixed;z-index:99999;bottom:50px;left: 100px;background:#383131b0;color:white; padding: 0.5rem; display:none\" class=\"ssq-alert-container\" id=\"ssqalert\" >\n  <\/div>\n\n\t\t\t\n\t\t<style>\n\t\t\t.titoletto{ position: absolute;\r\n    text-align: center;\r\n    left: 50%;\r\n    width: 200px;\r\n    top: 20%;\r\n    margin: 0 0 0 -100px;\r\n    background: #000;\r\n}\r\n.mouser {\r\n\twidth: 50px;\r\n\theight: 90px;\r\n\tborder: 3px solid #fff;\r\n\tborder-radius: 60px;\r\n\tposition: relative;\r\nmargin:0 auto;}\r\n\t.mouser::before {\r\n\t\tcontent: '';\r\n\t\twidth: 12px;\r\n\t\theight: 12px;\r\n\t\tposition: absolute;\r\n\t\ttop: 10px;\r\n\t\tleft: 50%;\r\n\t\ttransform: translateX(-50%);\r\n\t\tbackground-color: #fff;\r\n\t\tborder-radius: 50%;\r\n\t\topacity: 1;\r\n\t\tanimation: wheel 2s infinite;\r\n\t\t-webkit-animation: wheel 2s infinite;\r\n\t}\r\n@keyframes wheel {\r\n\tto {\r\n\t\topacity: 0;\r\n\t\ttop: 60px;\r\n\t}\r\n}\r\n\r\n@-webkit-keyframes wheel {\r\n\tto {\r\n\t\topacity: 0;\r\n\t\ttop: 60px;\r\n\t}\r\n}\r\n.scrollo {\r\n\twidth: 60px;\r\n\theight: 60px;\r\n\tborder: 2px solid #fff;\r\n\tborder-radius: 50%;\r\n\tposition: relative;\r\nmargin:0 auto;\r\n\tanimation: down 1.5s infinite;\r\n\t-webkit-animation: down 1.5s infinite;}\r\n\t.scrollo::before {\r\n\t\tcontent: '';\r\n\t\tposition: absolute;\r\n\t\ttop: 15px;\r\n\t\tleft: 18px;\r\n\t\twidth: 18px;\r\n\t\theight: 18px;\r\n\t\tborder-left: 2px solid #fff;\r\n  \tborder-bottom: 2px solid #fff;\r\n\t\ttransform: rotate(-45deg);\r\n\t}\r\n@keyframes down {\r\n\t0% {\r\n\t\ttransform: translate(0);\r\n\t}\r\n\t20% {\r\n\t\ttransform: translateY(15px);\r\n\t}\r\n\t40% {\r\n\t\ttransform: translate(0);\r\n\t}\r\n}\r\n\r\n@-webkit-keyframes down {\r\n\t0% {\r\n\t\ttransform: translate(0);\r\n\t}\r\n\t20% {\r\n\t\ttransform: translateY(15px);\r\n\t}\r\n\t40% {\r\n\t\ttransform: translate(0);\r\n\t}\r\n}\r\np.green {\r\n    color: #12c54f;\r\n    font-size: 2em;\r\n    line-height: 10px;\r\n    letter-spacing: 2px;\r\n    text-transform: uppercase;\r\n    text-align: left;}\r\n.scroll{\r\nposition: absolute;\r\nleft: 50%;\r\ntop: 50%;\r\ntransform: translate(-50%, -50%);\r\ntext-align: center;\r\ncolor:#fff;\r\n}\r\n#testo_scroll{color:#fff; letter-spacing: 2px; }\r\n.scrollsequence-pages-wrap{border:solid #000}\n\t\t<\/style>\n\t\t\t\t\n<section class=\"scrollsequence-wrap ssq-wrap-0 \" id=\"ssq-uid-28347-0-33604\" style=\";height: calc(100vh + 22090px);padding:0;margin:0; margin-top:0;margin-bottom:0; width:100%; max-width:initial;box-sizing: border-box;border:-1px dashed blue;\">\n  \t<div class=\"scrollsequence-sticky\" style=\"position:relative;box-sizing: border-box;\">\n  \t\t<canvas class=\"scrollsequence-canvas\" style=\"position:absolute;\"><\/canvas>\n\t\t<div class=\"scrollsequence-pages-wrap\" style=\"position:relative; margin:0; padding:0; box-sizing: border-box;\">\n\n\t\t<div class=\"scrollsequence-page\" id=\"ssq-page-0-0\" style=\"box-sizing: border-box;height:100vh;width:100%;overflow:hidden!important;\">\n\t\t\t\t<div class=\"titolo scroll\">\n<h1 id=\"testo_scroll\">\u0412\u043e\u0434\u0430 &#8211; \u044d\u0442\u043e<\/h1>\n<p class=\"green\">\u0417\u0414\u041e\u0420\u041e\u0412\u042c\u0415<\/p>\n<\/div>\n<div class=\"titolo2 scroll\">\n<h1 id=\"testo_scroll\">\u0420\u041e\u0421\u0422<\/h1>\n<p class=\"green\">crescita<\/p>\n<\/div>\n<div class=\"titolo3 scroll\">\n<h1 id=\"testo_scroll\">\u0412\u043e\u0434\u0430 &#8211; \u044d\u0442\u043e<\/h1>\n<p class=\"green\">\u0416\u0418\u0417\u041d\u042c.<\/p>\n<\/div>\n\n\t\t<\/div>  \n\t\t\t\t \n\t\t<div class=\"scrollsequence-page\" id=\"ssq-page-0-1\" style=\"box-sizing: border-box;height:100vh;width:100%;overflow:hidden!important;\">\n\t\t\t\t<div class=\"titolo4 scroll\">\n<h3 id=\"testo_scroll\">\u041c\u044b \u0442\u0435\u0447\u0435\u043c, \u0440\u0430\u0437\u0432\u0438\u0432\u0430\u0435\u043c\u0441\u044f \u0438 \u0430\u0434\u0430\u043f\u0442\u0438\u0440\u0443\u0435\u043c\u0441\u044f \u043f\u043e\u0434\u043e\u0431\u043d\u043e \u0432\u043e\u0434\u0435.<\/h3>\n<\/div>\n<div class=\"titolo5 scroll\">\n<h3 id=\"testo_scroll\">\u042d\u043b\u0435\u043c\u0435\u043d\u0442 \u0436\u0438\u0437\u043d\u0435\u043d\u043d\u043e\u0439 \u0432\u0430\u0436\u043d\u043e\u0441\u0442\u0438. \u0421 \u0435\u0435 \u0449\u0435\u0434\u0440\u043e\u0441\u0442\u044c\u044e \u043d\u0430\u0441 \u0441\u0432\u044f\u0437\u044b\u0432\u0430\u0435\u0442 \u0443\u0432\u0430\u0436\u0435\u043d\u0438\u0435 \u0438 \u0447\u0438\u0441\u0442\u0430\u044f \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u043d\u043e\u0441\u0442\u044c.<\/h3>\n<\/div>\n\n\t\t<\/div>  \n\t\t\t\t \n\t\t<div class=\"scrollsequence-page\" id=\"ssq-page-0-2\" style=\"box-sizing: border-box;height:100vh;width:100%;overflow:hidden!important;\">\n\t\t\t\t<div class=\"titolo6 scroll\">\n<h3 id=\"testo_scroll\">\u0421 1982 \u0433\u043e\u0434\u0430 \u043c\u044b \u0440\u0430\u0437\u0440\u0430\u0431\u0430\u0442\u044b\u0432\u0430\u0435\u043c \u0438 \u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u043c \u043d\u0430\u0434\u0435\u0436\u043d\u044b\u0435 \u0438 \u0441\u043e\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u044b\u0435 \u0438\u043d\u0441\u0442\u0440\u0443\u043c\u0435\u043d\u0442\u044b \u0434\u043b\u044f \u043e\u0447\u0438\u0441\u0442\u043a\u0438 \u0432\u043e\u0434\u044b \u0438 \u0434\u043e\u0437\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f \u0445\u0438\u043c\u0438\u0447\u0435\u0441\u043a\u0438\u0445 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u043e\u0432.<\/h3>\n<\/div>\n\n\t\t<\/div>  \n\t\t\t\t \n\t\t<div class=\"scrollsequence-page\" id=\"ssq-page-0-3\" style=\"box-sizing: border-box;height:100vh;width:100%;overflow:hidden!important;\">\n\t\t\t\t<div class=\"titolo7 scroll\">\n<h3 id=\"testo_scroll\">\u041c\u044b &#8211; \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u044f, \u043e\u0442\u043a\u0440\u044b\u0442\u0430\u044f \u0434\u043b\u044f \u0438\u0437\u043c\u0435\u043d\u0435\u043d\u0438\u0439, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u043c\u044b \u0434\u0435\u0439\u0441\u0442\u0432\u0443\u0435\u0442 \u043d\u0430 \u043e\u0441\u043d\u043e\u0432\u0435 \u0442\u0440\u0435\u0445 \u043e\u0441\u043d\u043e\u0432\u043d\u044b\u0445 \u0444\u0430\u043a\u0442\u043e\u0440\u043e\u0432:<\/h3>\n<\/div>\n\n\t\t<\/div>  \n\t\t\t\t \n\t\t<div class=\"scrollsequence-page\" id=\"ssq-page-0-4\" style=\"box-sizing: border-box;height:100vh;width:100%;overflow:hidden!important;\">\n\t\t\t\t\n\t\t<\/div>  \n\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div><!-- .scrollsequence-sticky -->\n\n\n<\/section><!-- .scrollsequence-wrap -->\n\t\t<script class=\"scrollsequence-input-script\">\n\t\tvar ssqInput={};\n\t\t\t\tssqInput={\"debug\":[],\"show_footer\":true,\"show_sidebar\":false,\"preloadPercentage\":\"0.12\",\"ssqFyiId\":33604,\"siteUrl\":\"https:\\\/\\\/www.emecpumps.com\"};\n\t\t\t\tssqInput.sc=[];\n\t\t\t\tssqInput.sc[0]={\"ssqId\":33604,\"bodyBgColor\":\"#000000\",\"imageOpacity\":\"0.99\",\"scrub\":1,\"forceFullWidth\":0,\"zIndex\":null,\"triggerStart\":\"1\",\"triggerEnd\":\"0\",\"canvasDPR\":\"quality\",\"page\":[{\"alignX\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"alignY\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"imgDur\":20,\"scaleTo\":{\"desktop\":\"fill\",\"mobile\":\"fill\"},\"animEl\":[{\"_type\":\"ssqnce_anim_io\",\"ssqnce_anim_io_id\":\".titolo\",\"ssqnce_anim_io_start\":\"5\",\"ssqnce_anim_io_end\":\"65\",\"ssqnce_separator_in\":\"\",\"ssqnce_anim_io_in_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_y\",\"ssqnce_anim_io_value\":\"-150\"}],\"ssqnce_anim_io_in_duration\":\"20\",\"ssqnce_separator_out\":\"\",\"ssqnce_anim_io_out_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_y\",\"ssqnce_anim_io_value\":\"150\"}],\"ssqnce_anim_io_out_duration\":\"15\"},{\"_type\":\"ssqnce_anim_io\",\"ssqnce_anim_io_id\":\".titolo2\",\"ssqnce_anim_io_start\":\"60\",\"ssqnce_anim_io_end\":\"115\",\"ssqnce_separator_in\":\"\",\"ssqnce_anim_io_in_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_y\",\"ssqnce_anim_io_value\":\"-100\"}],\"ssqnce_anim_io_in_duration\":\"15\",\"ssqnce_separator_out\":\"\",\"ssqnce_anim_io_out_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_y\",\"ssqnce_anim_io_value\":\"109\"}],\"ssqnce_anim_io_out_duration\":\"15\"},{\"_type\":\"ssqnce_anim_io\",\"ssqnce_anim_io_id\":\".titolo3\",\"ssqnce_anim_io_start\":\"120\",\"ssqnce_anim_io_end\":\"179\",\"ssqnce_separator_in\":\"\",\"ssqnce_anim_io_in_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_y\",\"ssqnce_anim_io_value\":\"-111\"}],\"ssqnce_anim_io_in_duration\":\"15\",\"ssqnce_separator_out\":\"\",\"ssqnce_anim_io_out_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_y\",\"ssqnce_anim_io_value\":\"113\"}],\"ssqnce_anim_io_out_duration\":\"15\"}],\"imagesFull\":[\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0000.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0001.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0002.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0003.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0004.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0005.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0006.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0007.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0008.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0009.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0010.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0011.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0012.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0013.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0014.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0015.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0016.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0017.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0018.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0019.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0020.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0021.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0022.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0023.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0024.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0025.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0026.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0027.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0028.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0029.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0030.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0031.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0032.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0033.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0034.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0035.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0036.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0037.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0038.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0039.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0040.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0041.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0042.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0043.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0044.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0045.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0046.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0047.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0048.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0049.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0050.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0051.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0052.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0053.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0054.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0055.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0056.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0057.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0058.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0059.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0060.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0061.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0062.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0063.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0064.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0065.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0066.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0067.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0068.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0069.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0070.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0071.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0072.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0073.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0074.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0075.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0076.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0077.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0078.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0079.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0080.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0081.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0082.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0083.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0084.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0085.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0086.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0087.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0088.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0089.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0090.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0091.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0092.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0093.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0094.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0095.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0096.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0097.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0098.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0099.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0100.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0101.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0102.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0103.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0104.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0105.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0106.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0107.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0108.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0109.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0110.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0111.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0112.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0113.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0114.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0115.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0116.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0117.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0118.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0119.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0120.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0121.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0122.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0123.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0124.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0125.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0126.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0127.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0128.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0129.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0130.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0131.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0132.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0133.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0134.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0135.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0136.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0137.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0138.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0139.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0140.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0141.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0142.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0143.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0144.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0145.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0146.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0147.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0148.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0149.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0150.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0151.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0152.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0153.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0154.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0155.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0156.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0157.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0158.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0159.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0160.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0161.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0162.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0163.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0164.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0165.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0166.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0167.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0168.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0169.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0170.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0171.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0172.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0173.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0174.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0175.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0176.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0177.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0178.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0179.jpg\"],\"imagesLength\":180,\"animElLength\":3,\"pageSpacer\":3600,\"pageAbsBegin\":0,\"pageAbsEnd\":3600},{\"alignX\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"alignY\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"imgDur\":25,\"scaleTo\":{\"desktop\":\"fill\",\"mobile\":\"fill\"},\"animEl\":[{\"_type\":\"ssqnce_anim_io\",\"ssqnce_anim_io_id\":\".titolo4\",\"ssqnce_anim_io_start\":\"5\",\"ssqnce_anim_io_end\":\"60\",\"ssqnce_separator_in\":\"\",\"ssqnce_anim_io_in_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"}],\"ssqnce_anim_io_in_duration\":\"15\",\"ssqnce_separator_out\":\"\",\"ssqnce_anim_io_out_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"}],\"ssqnce_anim_io_out_duration\":\"15\"},{\"_type\":\"ssqnce_anim_io\",\"ssqnce_anim_io_id\":\".titolo5\",\"ssqnce_anim_io_start\":\"80\",\"ssqnce_anim_io_end\":\"130\",\"ssqnce_separator_in\":\"\",\"ssqnce_anim_io_in_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"}],\"ssqnce_anim_io_in_duration\":\"15\",\"ssqnce_separator_out\":\"\",\"ssqnce_anim_io_out_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"}],\"ssqnce_anim_io_out_duration\":\"15\"}],\"imagesFull\":[\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20000.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20001.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20002.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20003.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20004.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20005.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20006.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20007.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20008.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20009.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20010.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20011.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20012.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20013.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20014.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20015.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20016.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20017.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20018.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20019.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20020.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20021.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20022.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20023.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20024.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20025.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20026.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20027.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20028.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20029.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20030.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20031.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20032.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20033.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20034.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20035.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20036.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20037.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20038.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20039.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20040.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20041.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20042.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20043.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20044.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20045.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20046.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20047.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20048.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20049.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20050.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20051.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20052.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20053.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20054.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20055.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20056.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20057.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20058.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20059.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20060.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20061.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20062.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20063.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20064.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20065.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20066.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20067.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20068.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20069.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20070.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20071.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20072.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20073.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20074.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20075.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20076.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20077.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20078.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20079.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20080.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20081.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20082.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20083.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20084.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20085.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20086.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20087.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20088.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20089.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20090.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20091.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20092.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20093.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20094.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20095.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20096.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20097.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20098.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20099.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20100.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20101.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20102.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20103.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20104.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20105.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20106.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20107.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20108.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20109.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20110.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20111.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20112.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20113.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20114.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20115.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20116.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20117.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20118.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20119.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20120.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20121.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20122.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20123.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20124.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20125.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20126.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20127.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20128.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20129.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20130.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20131.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20132.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20133.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro_20134.jpg\"],\"imagesLength\":135,\"animElLength\":2,\"pageSpacer\":3375,\"pageAbsBegin\":3600,\"pageAbsEnd\":6975},{\"alignX\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"alignY\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"imgDur\":25,\"scaleTo\":{\"desktop\":\"fill\",\"mobile\":\"fill\"},\"animEl\":[{\"_type\":\"ssqnce_anim_io\",\"ssqnce_anim_io_id\":\".titolo6\",\"ssqnce_anim_io_start\":\"4\",\"ssqnce_anim_io_end\":\"80\",\"ssqnce_separator_in\":\"\",\"ssqnce_anim_io_in_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_x\",\"ssqnce_anim_io_value\":\"-71\"}],\"ssqnce_anim_io_in_duration\":\"15\",\"ssqnce_separator_out\":\"\",\"ssqnce_anim_io_out_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"},{\"_type\":\"ssqnce_anim_io_x\",\"ssqnce_anim_io_value\":\"82\"}],\"ssqnce_anim_io_out_duration\":\"15\"}],\"imagesFull\":[\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0000-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0001-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0002-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0003-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0004-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0005-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0006-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0007-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0008-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0009-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0010-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0011-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0012-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0013-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0014-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0015-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0016-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0017-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0018-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0019-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0020-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0021-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0022-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0023-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0024-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0025-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0026-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0027-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0028-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0029-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0030-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0031-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0032-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0033-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0034-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0035-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0036-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0037-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0038-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0039-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0040-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0041-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0042-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0043-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0044-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0045-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0046-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0047-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0048-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0049-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0050-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0051-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0052-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0053-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0054-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0055-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0056-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0057-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0058-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0059-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0060-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0061-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0062-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0063-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0064-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0065-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0066-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0067-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0068-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0069-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0070-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0071-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0072-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0073-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0074-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0075-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0076-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0077-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0078-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0079-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0080-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0081-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0082-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0083-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0084-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0085-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0086-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0087-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0088-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0089-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0090-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0091-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0092-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0093-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0094-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0095-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0096-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0097-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0098-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0099-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0100-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0101-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0102-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0103-3.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/web_intro0104-3.jpg\"],\"imagesLength\":105,\"animElLength\":1,\"pageSpacer\":2625,\"pageAbsBegin\":6975,\"pageAbsEnd\":9600},{\"alignX\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"alignY\":{\"desktop\":\"1\",\"mobile\":\"0.5\"},\"imgDur\":40,\"scaleTo\":{\"desktop\":\"0.9\",\"mobile\":\"fit\"},\"animEl\":[{\"_type\":\"ssqnce_anim_io\",\"ssqnce_anim_io_id\":\".titolo7\",\"ssqnce_anim_io_start\":\"0\",\"ssqnce_anim_io_end\":\"60\",\"ssqnce_separator_in\":\"\",\"ssqnce_anim_io_in_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"}],\"ssqnce_anim_io_in_duration\":\"15\",\"ssqnce_separator_out\":\"\",\"ssqnce_anim_io_out_list\":[{\"_type\":\"ssqnce_anim_io_fade\",\"ssqnce_anim_io_value\":\"0\"}],\"ssqnce_anim_io_out_duration\":\"15\"}],\"imagesFull\":[\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0000.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0001.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0002.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0003.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0004.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0005.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0006.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0007.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0008.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0009.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0010.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0011.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0012.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0013.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0014.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0015.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0016.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0017.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0018.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0019.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0020.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0021.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0022.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0023.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0024.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0025.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0026.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0027.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0028.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0029.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0030.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0031.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0032.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0033.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0034.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0035.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0036.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0037.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0038.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0039.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0040.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0041.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0042.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0043.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0044.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0045.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0046.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0047.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0048.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0049.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0050.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0051.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0052.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0053.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0054.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0055.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0056.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0057.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0058.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0059.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0060.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0061.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0062.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0063.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0064.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0065.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0066.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0067.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0068.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0069.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0070.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0071.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0072.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0073.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0074.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0075.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0076.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0077.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0078.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0079.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0080.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0081.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0082.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0083.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0084.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0085.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0086.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0087.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0088.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0089.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0090.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0091.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0092.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0093.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0094.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0095.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0096.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0097.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0098.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0099.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0100.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0101.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0102.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0103.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0104.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0105.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0106.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0107.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0108.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0109.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0110.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0111.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0112.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0113.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0114.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0115.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0116.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0117.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0118.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0119.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0120.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0121.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0122.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0123.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0124.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0125.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0126.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0127.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0128.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0129.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0130.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0131.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0132.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0133.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0134.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0135.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0136.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0137.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0138.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0139.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0140.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0141.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0142.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0143.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0144.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0145.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0146.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0147.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0148.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0149.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0150.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0151.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0152.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0153.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0154.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0155.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0156.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0157.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0158.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0159.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0160.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0161.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0162.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0163.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0164.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0165.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0166.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0167.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0168.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0169.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0170.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0171.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0172.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0173.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0174.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0175.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0176.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0177.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0178.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0179.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0180.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0181.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0182.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0183.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0184.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0185.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0186.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0187.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0188.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0189.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0190.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0191.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0192.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0193.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0194.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0195.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0196.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0197.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0198.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0199.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0200.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0201.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0202.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0203.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0204.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0205.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0206.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0207.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0208.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0209.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cerchi_ru0210.jpg\"],\"imagesLength\":211,\"animElLength\":1,\"pageSpacer\":8440,\"pageAbsBegin\":9600,\"pageAbsEnd\":18040},{\"alignX\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"alignY\":{\"desktop\":\"0.5\",\"mobile\":\"0.5\"},\"imgDur\":25,\"scaleTo\":{\"desktop\":\"fill\",\"mobile\":\"fill\"},\"animEl\":[],\"imagesFull\":[\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20000.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20001.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20002.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20003.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20004.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20005.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20006.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20007.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20008.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20009.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20010.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20011.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20012.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20013.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20014.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20015.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20016.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20017.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20018.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20019.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20020.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20021.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20022.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20023.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20024.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20025.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20026.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20027.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20028.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20029.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20030.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20031.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20032.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20033.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20034.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20035.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20036.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20037.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20038.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20039.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20040.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20041.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20042.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20043.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20044.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20045.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20046.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20047.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20048.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20049.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20050.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20051.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20052.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20053.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20054.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20055.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20056.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20057.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20058.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20059.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20060.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20061.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20062.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20063.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20064.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20065.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20066.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20067.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20068.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20069.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20070.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20071.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20072.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20073.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20074.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20075.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20076.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20077.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20078.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20079.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20080.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20081.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20082.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20083.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20084.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20085.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20086.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20087.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20088.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20089.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20090.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20091.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20092.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20093.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20094.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20095.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20096.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20097.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20098.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20099.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20100.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20101.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20102.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20103.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20104.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20105.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20106.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20107.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20108.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20109.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20110.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20111.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20112.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20113.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20114.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20115.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20116.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20117.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20118.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20119.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20120.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20121.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20122.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20123.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20124.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20125.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20126.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20127.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20128.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20129.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20130.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20131.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20132.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20133.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20134.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20135.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20136.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20137.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20138.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20139.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20140.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20141.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20142.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20143.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20144.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20145.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20146.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20147.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20148.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20149.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20150.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20151.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20152.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20153.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20154.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20155.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20156.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20157.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20158.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20159.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20160.jpg\",\"https:\\\/\\\/www.emecpumps.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Composizione-20161.jpg\"],\"imagesLength\":162,\"animElLength\":0,\"pageSpacer\":4050,\"pageAbsBegin\":18040,\"pageAbsEnd\":22090}],\"pageLength\":5,\"scSpacer\":22090,\"position\":\"sticky-js\"};\n\t\t<\/script>\n<\/scrollsequence>\n\t\t[\/vc_column_text][vc_raw_js]JTIwJTNDc2NyaXB0JTNFalF1ZXJ5JTI4ZnVuY3Rpb24lMjglMjQlMjklMjAlN0IlMEElMjQlMjglMjIuY3Vyc29yJTIyJTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjQlMjglMjIuc2Nyb2xsc2VxdWVuY2Utd3JhcCUyMiUyOS5tb3VzZW1vdmUlMjhmdW5jdGlvbiUyMCUyOGUlMjklMjAlN0IlMEElMjAlMjAlMjAlMjAlMjQlMjglMjIuY3Vyc29yJTIyJTI5LnNob3clMjglMjkuY3NzJTI4JTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIybGVmdCUyMiUzQSUyMGUuY2xpZW50WCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMnRvcCUyMiUzQSUyMGUuY2xpZW50WSUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUyMCUyMCU3RCUyOS5tb3VzZW91dCUyOGZ1bmN0aW9uJTIwJTI4JTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwJTI0JTI4JTIyLmN1cnNvciUyMiUyOS5oaWRlJTI4JTI5JTNCJTBBJTIwJTIwJTdEJTI5JTNCJTBBJTdEJTI5JTNCJTNDJTJGc2NyaXB0JTNF[\/vc_raw_js][\/vc_column][\/vc_row]<\/div>","protected":false},"excerpt":{"rendered":"[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; pix_particles_check=&#8221;&#8221; css=&#8221;.vc_custom_1616411280682{background-color: #000000 !important;}&#8221;][vc_column][vc_column_text] Scroll Down &nbsp; [\/vc_column_text][vc_raw_js]JTIwJTNDc2NyaXB0JTNFalF1ZXJ5JTI4ZnVuY3Rpb24lMjglMjQlMjklMjAlN0IlMEElMjQlMjglMjIuY3Vyc29yJTIyJTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjQlMjglMjIuc2Nyb2xsc2VxdWVuY2Utd3JhcCUyMiUyOS5tb3VzZW1vdmUlMjhmdW5jdGlvbiUyMCUyOGUlMjklMjAlN0IlMEElMjAlMjAlMjAlMjAlMjQlMjglMjIuY3Vyc29yJTIyJTI5LnNob3clMjglMjkuY3NzJTI4JTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIybGVmdCUyMiUzQSUyMGUuY2xpZW50WCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMnRvcCUyMiUzQSUyMGUuY2xpZW50WSUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUyMCUyMCU3RCUyOS5tb3VzZW91dCUyOGZ1bmN0aW9uJTIwJTI4JTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwJTI0JTI4JTIyLmN1cnNvciUyMiUyOS5oaWRlJTI4JTI5JTNCJTBBJTIwJTIwJTdEJTI5JTNCJTBBJTdEJTI5JTNCJTNDJTJGc2NyaXB0JTNF[\/vc_raw_js][\/vc_column][\/vc_row]","protected":false},"author":1,"featured_media":28163,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"lazy_load_responsive_images_disabled":false,"footnotes":""},"class_list":["post-28347","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430 - Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430 - Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; pix_particles_check=&#8221;&#8221; css=&#8221;.vc_custom_1616411280682{background-color: #000000 !important;}&#8221;][vc_column][vc_column_text] Scroll Down &nbsp; [\/vc_column_text][vc_raw_js]JTIwJTNDc2NyaXB0JTNFalF1ZXJ5JTI4ZnVuY3Rpb24lMjglMjQlMjklMjAlN0IlMEElMjQlMjglMjIuY3Vyc29yJTIyJTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjQlMjglMjIuc2Nyb2xsc2VxdWVuY2Utd3JhcCUyMiUyOS5tb3VzZW1vdmUlMjhmdW5jdGlvbiUyMCUyOGUlMjklMjAlN0IlMEElMjAlMjAlMjAlMjAlMjQlMjglMjIuY3Vyc29yJTIyJTI5LnNob3clMjglMjkuY3NzJTI4JTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIybGVmdCUyMiUzQSUyMGUuY2xpZW50WCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMnRvcCUyMiUzQSUyMGUuY2xpZW50WSUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUyMCUyMCU3RCUyOS5tb3VzZW91dCUyOGZ1bmN0aW9uJTIwJTI4JTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwJTI0JTI4JTIyLmN1cnNvciUyMiUyOS5oaWRlJTI4JTI5JTNCJTBBJTIwJTIwJTdEJTI5JTNCJTBBJTdEJTI5JTNCJTNDJTJGc2NyaXB0JTNF[\/vc_raw_js][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/\" \/>\n<meta property=\"og:site_name\" content=\"Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/emecpumps\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-08T22:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2369\" \/>\n\t<meta property=\"og:image:height\" content=\"1544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EMECpumps\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u043c\u0438\u043d\u0443\u0442\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/\",\"url\":\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/\",\"name\":\"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430 - Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438\",\"isPartOf\":{\"@id\":\"https:\/\/www.emecpumps.com\/ru\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg\",\"datePublished\":\"2020-11-24T13:28:33+00:00\",\"dateModified\":\"2022-02-08T22:15:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#primaryimage\",\"url\":\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg\",\"contentUrl\":\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg\",\"width\":2369,\"height\":1544},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.emecpumps.com\/ru\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emecpumps.com\/ru\/#website\",\"url\":\"https:\/\/www.emecpumps.com\/ru\/\",\"name\":\"Emec Pumps - Pompe dosatrici e Sistemi di disinfezione\",\"description\":\"\u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438\",\"publisher\":{\"@id\":\"https:\/\/www.emecpumps.com\/ru\/#organization\"},\"alternateName\":\"Emec\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emecpumps.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emecpumps.com\/ru\/#organization\",\"name\":\"Emec Pumps - Pompe dosatrici e Sistemi di disinfezione\",\"url\":\"https:\/\/www.emecpumps.com\/ru\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/www.emecpumps.com\/ru\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2024\/01\/logo_emec.png\",\"contentUrl\":\"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2024\/01\/logo_emec.png\",\"width\":470,\"height\":133,\"caption\":\"Emec Pumps - Pompe dosatrici e Sistemi di disinfezione\"},\"image\":{\"@id\":\"https:\/\/www.emecpumps.com\/ru\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/emecpumps\",\"https:\/\/x.com\/EMECpumps\",\"https:\/\/www.instagram.com\/emecpumps\/\",\"https:\/\/www.linkedin.com\/company\/2715607\/admin\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430 - Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/","og_locale":"ru_RU","og_type":"article","og_title":"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430 - Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438","og_description":"[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; pix_particles_check=&#8221;&#8221; css=&#8221;.vc_custom_1616411280682{background-color: #000000 !important;}&#8221;][vc_column][vc_column_text] Scroll Down &nbsp; [\/vc_column_text][vc_raw_js]JTIwJTNDc2NyaXB0JTNFalF1ZXJ5JTI4ZnVuY3Rpb24lMjglMjQlMjklMjAlN0IlMEElMjQlMjglMjIuY3Vyc29yJTIyJTI5LmhpZGUlMjglMjklM0IlMEElMjAlMjAlMjQlMjglMjIuc2Nyb2xsc2VxdWVuY2Utd3JhcCUyMiUyOS5tb3VzZW1vdmUlMjhmdW5jdGlvbiUyMCUyOGUlMjklMjAlN0IlMEElMjAlMjAlMjAlMjAlMjQlMjglMjIuY3Vyc29yJTIyJTI5LnNob3clMjglMjkuY3NzJTI4JTdCJTBBJTIwJTIwJTIwJTIwJTIwJTIwJTIybGVmdCUyMiUzQSUyMGUuY2xpZW50WCUyQyUwQSUyMCUyMCUyMCUyMCUyMCUyMCUyMnRvcCUyMiUzQSUyMGUuY2xpZW50WSUwQSUyMCUyMCUyMCUyMCU3RCUyOSUzQiUwQSUyMCUyMCU3RCUyOS5tb3VzZW91dCUyOGZ1bmN0aW9uJTIwJTI4JTI5JTIwJTdCJTBBJTIwJTIwJTIwJTIwJTI0JTI4JTIyLmN1cnNvciUyMiUyOS5oaWRlJTI4JTI5JTNCJTBBJTIwJTIwJTdEJTI5JTNCJTBBJTdEJTI5JTNCJTNDJTJGc2NyaXB0JTNF[\/vc_raw_js][\/vc_column][\/vc_row]","og_url":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/","og_site_name":"Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438","article_publisher":"https:\/\/www.facebook.com\/emecpumps","article_modified_time":"2022-02-08T22:15:01+00:00","og_image":[{"width":2369,"height":1544,"url":"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EMECpumps","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"1 \u043c\u0438\u043d\u0443\u0442\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/","url":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/","name":"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430 - Emec - \u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438","isPartOf":{"@id":"https:\/\/www.emecpumps.com\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#primaryimage"},"image":{"@id":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg","datePublished":"2020-11-24T13:28:33+00:00","dateModified":"2022-02-08T22:15:01+00:00","breadcrumb":{"@id":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emecpumps.com\/ru\/simple-as-water\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#primaryimage","url":"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg","contentUrl":"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2021\/01\/logs.jpg","width":2369,"height":1544},{"@type":"BreadcrumbList","@id":"https:\/\/www.emecpumps.com\/ru\/simple-as-water\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emecpumps.com\/ru\/"},{"@type":"ListItem","position":2,"name":"\u043f\u0440\u043e\u0441\u0442\u043e\u0439 \u043a\u0430\u043a \u0432\u043e\u0434\u0430"}]},{"@type":"WebSite","@id":"https:\/\/www.emecpumps.com\/ru\/#website","url":"https:\/\/www.emecpumps.com\/ru\/","name":"Emec Pumps - Pompe dosatrici e Sistemi di disinfezione","description":"\u0414\u043e\u0437\u0438\u0440\u0443\u044e\u0449\u0438\u0435 \u043d\u0430\u0441\u043e\u0441\u044b \u0438 \u0441\u0438\u0441\u0442\u0435\u043c\u044b \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u0438","publisher":{"@id":"https:\/\/www.emecpumps.com\/ru\/#organization"},"alternateName":"Emec","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emecpumps.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/www.emecpumps.com\/ru\/#organization","name":"Emec Pumps - Pompe dosatrici e Sistemi di disinfezione","url":"https:\/\/www.emecpumps.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/www.emecpumps.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2024\/01\/logo_emec.png","contentUrl":"https:\/\/www.emecpumps.com\/wp-content\/uploads\/2024\/01\/logo_emec.png","width":470,"height":133,"caption":"Emec Pumps - Pompe dosatrici e Sistemi di disinfezione"},"image":{"@id":"https:\/\/www.emecpumps.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/emecpumps","https:\/\/x.com\/EMECpumps","https:\/\/www.instagram.com\/emecpumps\/","https:\/\/www.linkedin.com\/company\/2715607\/admin\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/pages\/28347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/comments?post=28347"}],"version-history":[{"count":5,"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/pages\/28347\/revisions"}],"predecessor-version":[{"id":55963,"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/pages\/28347\/revisions\/55963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/media\/28163"}],"wp:attachment":[{"href":"https:\/\/www.emecpumps.com\/ru\/wp-json\/wp\/v2\/media?parent=28347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}